{"id":14903,"date":"2020-12-06T15:51:17","date_gmt":"2020-12-06T15:51:17","guid":{"rendered":"https:\/\/ebay.luba.de\/index.php\/product\/kornkraft-getreidebehalter-moritz-2-kg\/"},"modified":"2022-11-28T14:09:27","modified_gmt":"2022-11-28T14:09:27","slug":"kornkraft-getreidebehalter-moritz-2-kg","status":"publish","type":"product","link":"https:\/\/ebay.luba.de\/index.php\/product\/kornkraft-getreidebehalter-moritz-2-kg\/","title":{"rendered":"Kornkraft Getreidebeh\u00e4lter Moritz 2 kg"},"content":{"rendered":"<p>Diese Getreidebeh\u00e4lter machen in jeder Vollwert-K\u00fcche eine gute Figur.<br \/>\nUnd das Sichtfenster aus Echtglas informiert Sie jederzeit \u00fcber den Stand Ihrer Vorr\u00e4te.<\/p>\n<p>Atmungsaktives L\u00e4rchenholz, mit Bienenwachsbalsam behandelt, verhindert Staun\u00e4sse.<\/p>\n<ul>\n<li>F\u00fcllmenge: 2 kg Getreide<\/li>\n<li>Verschlu\u00df: Pa\u00dffalz<\/li>\n<li>Ma\u00dfe: H\u00f6he: 27 cm, Breite: 18 cm, Tiefe: 15 cm<\/li>\n<li>Gewicht: 2 kg<\/li>\n<li>Garantie: 5 Jahre<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Diese Getreidebeh\u00e4lter machen in jeder Vollwert-K\u00fcche eine gute Figur. Und das Sichtfenster aus Echtglas informiert Sie jederzeit \u00fcber den Stand Ihrer Vorr\u00e4te. Atmungsaktives L\u00e4rchenholz, mit Bienenwachsbalsam behandelt, verhindert Staun\u00e4sse. F\u00fcllmenge: 2 kg Getreide Verschlu\u00df: Pa\u00dffalz Ma\u00dfe: H\u00f6he: 27 cm, Breite: 18 cm, Tiefe: 15 cm Gewicht: 2 kg Garantie: 5 Jahre<\/p>\n","protected":false},"featured_media":15888,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[224,225,199],"product_tag":[],"class_list":{"0":"post-14903","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aufbewahrung","7":"product_cat-getreidespeicher","8":"product_cat-kuchenhelfer","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/product\/14903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/comments?post=14903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/media\/15888"}],"wp:attachment":[{"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/media?parent=14903"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/product_brand?post=14903"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/product_cat?post=14903"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ebay.luba.de\/index.php\/wp-json\/wp\/v2\/product_tag?post=14903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}